{"id":7709,"date":"2026-01-27T13:54:49","date_gmt":"2026-01-27T12:54:49","guid":{"rendered":"https:\/\/maloglaus.com\/?page_id=7709"},"modified":"2026-05-07T15:13:53","modified_gmt":"2026-05-07T13:13:53","slug":"malo-glaus-communication-visuelle","status":"publish","type":"page","link":"https:\/\/maloglaus.com\/en\/malo-glaus-communication-visuelle\/","title":{"rendered":"Malo Glaus | Communication visuelle"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"7709\" class=\"elementor elementor-7709\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6e944ddd e-con-full elementor-hidden-mobile e-flex e-con e-parent\" data-id=\"6e944ddd\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9e798cd e-transform elementor-widget elementor-widget-heading\" data-id=\"9e798cd\" data-element_type=\"widget\" data-settings=\"{&quot;_transform_translateY_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:-207,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">MALO GLAUS | Communication visuelle<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d2edcd5 elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"d2edcd5\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-d80ff1b e-con-full e-flex e-con e-child\" data-id=\"d80ff1b\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-05cbc61 e-con-full e-flex e-con e-child\" data-id=\"05cbc61\" data-element_type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a8e2233 e-con-full e-flex e-con e-child\" data-id=\"a8e2233\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-2eae6cc e-flex e-con-boxed e-con e-child\" data-id=\"2eae6cc\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-392ba14 e-flex e-con-boxed e-con e-child\" data-id=\"392ba14\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ae57560 elementor-widget elementor-widget-heading\" data-id=\"ae57560\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">VISUAL COMMUNICATION<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-517f302 elementor-widget elementor-widget-text-editor\" data-id=\"517f302\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Unstpbl<\/p><p><a href=\"https:\/\/maloglaus.com\/en\/projet-trace-lab\/\">Trace Lab<\/a><\/p><p>Fire Sens<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e31661f elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"e31661f\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7f5b00e e-con-full e-flex e-con e-child\" data-id=\"7f5b00e\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-019025b e-con-full e-flex e-con e-child\" data-id=\"019025b\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-3e72684 e-flex e-con-boxed e-con e-child\" data-id=\"3e72684\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-732d26a elementor-widget elementor-widget-heading\" data-id=\"732d26a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">SERVICES <br>&amp; QUOTE<\/br><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-08513e5 elementor-widget elementor-widget-text-editor\" data-id=\"08513e5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3 style=\"margin-bottom: 1px;\"><a href=\"https:\/\/maloglaus.com\/en\/prestations-devis-photo\/\">Photo &amp; video services<\/a><\/h3><h3 style=\"margin-bottom: 1px;\"><a href=\"https:\/\/maloglaus.com\/en\/prestations-devis-site-web\/\">Website design<\/a><\/h3><h3 style=\"margin-bottom: 1px;\"><a href=\"https:\/\/maloglaus.com\/en\/prestations-devis-design-graphique\/\">Visual communication &amp; graphic design<\/a><\/h3><p><!-- 3 sauts de ligne avant \"Panier\" --><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d667634 e-con-full e-flex e-con e-child\" data-id=\"d667634\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-0e2973e e-con-full e-flex e-con e-child\" data-id=\"0e2973e\" data-element_type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-395cc9b elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"395cc9b\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-77265f9 e-con-full e-flex e-con e-child\" data-id=\"77265f9\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-cc8f074 e-con-full e-flex e-con e-child\" data-id=\"cc8f074\" data-element_type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d7fe753 e-con-full e-flex e-con e-child\" data-id=\"d7fe753\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-997d973 e-con-full e-flex e-con e-child\" data-id=\"997d973\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-7b14523 e-flex e-con-boxed e-con e-child\" data-id=\"7b14523\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8d5e59e elementor-widget elementor-widget-heading\" data-id=\"8d5e59e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ABOUT<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3775833 elementor-widget elementor-widget-text-editor\" data-id=\"3775833\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3 style=\"margin-bottom: 1px;\"><a href=\"https:\/\/maloglaus.com\/en\/biographie\/\">Biography<\/a><\/h3><h3 style=\"margin-bottom: 1px;\"><a href=\"https:\/\/maloglaus.com\/en\/contact\/\">Contact<\/a><\/h3><p><!-- 3 sauts de ligne avant \"Prestation & Devis\" --><\/p><h3 style=\"margin-bottom: 1px;\">\u00a0<\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3ebaef3 e-con-full elementor-hidden-desktop e-flex e-con e-parent\" data-id=\"3ebaef3\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-935bc32 elementor-hidden-desktop elementor-hidden-tablet e-flex e-con-boxed e-con e-parent\" data-id=\"935bc32\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-69f5c9b elementor-widget elementor-widget-depicter_slider\" data-id=\"69f5c9b\" data-element_type=\"widget\" data-widget_type=\"depicter_slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<style id=\"depicter-149-inline-pre-css\">\n\n.depicter-149:not(.depicter-ready){\n\theight:700px;\n}\n\n\/***** Tablet *****\/\n@media screen and (max-width: 1024px){\n\n.depicter-149:not(.depicter-ready){\n\theight:700px;\n}\n\n}\n\/***** Mobile *****\/\n@media screen and (max-width: 767px){\n\n.depicter-149:not(.depicter-ready){\n\theight:740px;\n}\n\n}\n<\/style>\n<div id=\"depicter-149\" class=\"depicter depicter-document depicter-revert depicter-149 depicter-layout-fullwidth\">\n\n<div class=\"depicter-loading-container depicter-loading dotFlashing-dark\"><div class=\"depicter-loading-dark depicter-dot-flashing\">\n   <span><\/span>\n   <span><\/span>\n   <span><\/span>\n<\/div>\n<\/div>\n\n<div class=\"depicter-overlay-layers\">\n<a href=\"https:\/\/maloglaus.com\/en\/tirages-livres\/\"><h3 data-between-in-out=\"false\" data-mobile-animation-out=\"{'direction':'left','easing':'easeInOutCubic','duration':800,'movement':0,'type':'move'}\" id=\"depicter-149-element-3\" class=\"depicter-element depicter-layer depicter-149-element-3\" data-type=\"text\" data-wrap=\"true\" data-name=\"Text 1\" data-local-id=\"element-3\" data-offset=\"x:0px;y:0px;origin:tl\" data-mobile-offset=\"x:30px;y:441px;origin:tl\" data-position-type=\"absolute\" data-mobile-position-type=\"absolute\" data-hide-on-sections=\"depicter-149-section-1\" data-width=\"auto,,186px\" data-height=\"auto,,auto\" data-responsive-scale=\"true,,\">Website creation<\/h3><\/a>\n\n<a href=\"https:\/\/maloglaus.com\/en\/vetements\/\"><h3 data-between-in-out=\"false\" data-mobile-animation-out=\"{'direction':'left','easing':'easeInOutCubic','duration':800,'movement':0,'type':'move'}\" id=\"depicter-149-element-4\" class=\"depicter-element depicter-layer depicter-149-element-4\" data-type=\"text\" data-wrap=\"true\" data-name=\"Text 2\" data-local-id=\"element-4\" data-offset=\"x:30px;y:30px;origin:tl\" data-mobile-offset=\"x:30px;y:470px;origin:tl\" data-position-type=\"absolute\" data-mobile-position-type=\"absolute\" data-hide-on-sections=\"depicter-149-section-5\" data-width=\"auto,,auto\" data-height=\"auto,,auto\" data-responsive-scale=\"true,,\">Graphic design<\/h3><\/a>\n\n<a href=\"https:\/\/maloglaus.com\/en\/panier\/\"><h3 data-between-in-out=\"false\" data-mobile-animation-out=\"{'direction':'left','easing':'easeInOutCubic','duration':800,'movement':0,'type':'move'}\" id=\"depicter-149-element-7\" class=\"depicter-element depicter-layer depicter-149-element-7\" data-type=\"text\" data-wrap=\"true\" data-name=\"Text 4\" data-local-id=\"element-7\" data-offset=\"x:60px;y:60px;origin:tl\" data-mobile-offset=\"x:30px;y:498px;origin:tl\" data-position-type=\"absolute\" data-mobile-position-type=\"absolute\" data-hide-on-sections=\"depicter-149-section-9\" data-width=\"auto,,auto\" data-height=\"auto,,auto\" data-responsive-scale=\"true,,\">Mise en page de livres &amp; magazines<\/h3><\/a>\n\n<h2 id=\"depicter-149-element-39\" class=\"depicter-element depicter-layer depicter-149-element-39\" data-type=\"text\" data-wrap=\"true\" data-name=\"Text 5\" data-local-id=\"element-39\" data-offset=\"x:0px;y:0px;origin:tl\" data-mobile-offset=\"x:30px;y:14px;origin:tl\" data-position-type=\"absolute\" data-mobile-position-type=\"absolute\" data-width=\"auto,,310px\" data-height=\"auto,,auto\" data-responsive-scale=\"true,,\">COMMUNICATION <br>VISUELLE<br><\/h2>\n\n<\/div>\n\n<div id=\"depicter-149-section-1\" class=\"depicter-section depicter-149-section-1\" data-name=\"Section 1\" data-type=\"section\" data-local-id=\"section-1\">\n<picture data-between-in-out=\"false\" data-mobile-animation-in=\"{'direction':'left','easing':'easeInOutExpo','duration':800,'movement':0,'type':'move'}\" id=\"depicter-149-element-2\" class=\"depicter-element depicter-layer depicter-149-element-2\" data-type=\"image\" data-wrap=\"true\" data-name=\"Image 1\" data-local-id=\"element-2\" data-offset=\"x:57px;y:3px;origin:tl\" data-mobile-offset=\"x:30px;y:83px;origin:tl\" data-width=\"395px,,215px\" data-height=\"592px,,321px\" data-responsive-scale=\"true,,\" data-crop=\"false\">\n<source data-depicter-srcset=\"https:\/\/maloglaus.com\/wp-content\/uploads\/2025\/07\/DSC06619-scaled-e1753110362719-215x321.jpg, https:\/\/maloglaus.com\/wp-content\/uploads\/2025\/07\/DSC06619-scaled-e1753110362719-430x642.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(max-width: 767px)\" \/>\n\n<source data-depicter-srcset=\"https:\/\/maloglaus.com\/wp-content\/uploads\/2025\/07\/DSC06619-scaled-e1753110362719-329x494.jpg, https:\/\/maloglaus.com\/wp-content\/uploads\/2025\/07\/DSC06619-scaled-e1753110362719-658x988.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(min-width: 768px)\" \/>\n<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-depicter-src=\"https:\/\/maloglaus.com\/wp-content\/uploads\/2025\/07\/DSC06619-scaled-e1753110362719-329x494.jpg\" alt=\"ROD\u00c9O VWH | Malo Glaus\" \/>\n<\/picture>\n<a href=\"https:\/\/maloglaus.com\/en\/tirages-livres\/\"><h3 id=\"depicter-149-element-31\" class=\"depicter-element depicter-layer depicter-149-element-31\" data-type=\"text\" data-wrap=\"true\" data-name=\"Text 10\" data-local-id=\"element-31\" data-offset=\"x:0px;y:0px;origin:tl\" data-mobile-offset=\"x:-65px;y:81px;origin:mc\" data-width=\"auto,,auto\" data-height=\"auto,,auto\" data-responsive-scale=\"true,,\" data-frame-class=\"depicter-149-element-31-frame\">Website creation<\/h3><\/a>\n<\/div>\n\n<div id=\"depicter-149-section-5\" class=\"depicter-section depicter-149-section-5\" data-name=\"Slide 1\" data-type=\"section\" data-local-id=\"section-5\">\n<picture data-between-in-out=\"false\" data-mobile-animation-in=\"{'direction':'left','easing':'easeInOutExpo','duration':800,'movement':0,'type':'move'}\" id=\"depicter-149-element-16\" class=\"depicter-element depicter-layer depicter-149-element-16\" data-type=\"image\" data-wrap=\"true\" data-name=\"Image 4\" data-local-id=\"element-16\" data-offset=\"x:57px;y:3px;origin:tl\" data-mobile-offset=\"x:30px;y:83px;origin:tl\" data-width=\"395px,,213px\" data-height=\"592px,,320px\" data-responsive-scale=\"true,,\" data-crop=\"false\">\n<source data-depicter-srcset=\"https:\/\/maloglaus.com\/wp-content\/uploads\/2026\/01\/DSC09186-scaled-e1769162504352-213x320.jpg, https:\/\/maloglaus.com\/wp-content\/uploads\/2026\/01\/DSC09186-scaled-e1769162504352-426x640.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(max-width: 767px)\" \/>\n\n<source data-depicter-srcset=\"https:\/\/maloglaus.com\/wp-content\/uploads\/2026\/01\/DSC09186-scaled-e1769162504352-394x592.jpg, https:\/\/maloglaus.com\/wp-content\/uploads\/2026\/01\/DSC09186-scaled-e1769162504352-788x1184.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(min-width: 768px)\" \/>\n<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-depicter-src=\"https:\/\/maloglaus.com\/wp-content\/uploads\/2026\/01\/DSC09186-scaled-e1769162504352-394x592.jpg\" alt=\"DSC09186\" \/>\n<\/picture>\n<a href=\"https:\/\/maloglaus.com\/en\/vetements\/\"><p id=\"depicter-149-element-33\" class=\"depicter-element depicter-layer depicter-149-element-33\" data-type=\"text\" data-wrap=\"true\" data-name=\"Text 12\" data-local-id=\"element-33\" data-offset=\"x:30px;y:30px;origin:tl\" data-mobile-offset=\"x:-16px;y:110px;origin:mc\" data-width=\"auto,,269px\" data-height=\"auto,,auto\" data-responsive-scale=\"true,,\" data-frame-class=\"depicter-149-element-33-frame\">Graphic design<\/p><\/a>\n<\/div>\n\n<div id=\"depicter-149-section-9\" class=\"depicter-section depicter-149-section-9\" data-name=\"Slide 2\" data-type=\"section\" data-local-id=\"section-9\">\n<picture data-between-in-out=\"false\" data-mobile-animation-in=\"{'direction':'left','easing':'easeInOutExpo','duration':800,'movement':0,'type':'move'}\" id=\"depicter-149-element-18\" class=\"depicter-element depicter-layer depicter-149-element-18\" data-type=\"image\" data-wrap=\"true\" data-name=\"Image 6\" data-local-id=\"element-18\" data-offset=\"x:57px;y:3px;origin:tl\" data-mobile-offset=\"x:30px;y:83px;origin:tl\" data-width=\"395px,,213px\" data-height=\"592px,,320px\" data-responsive-scale=\"true,,\" data-crop=\"false\">\n<source data-depicter-srcset=\"https:\/\/maloglaus.com\/wp-content\/uploads\/2025\/07\/Sans-titre-21-avril-2025-10.54.45-32-760500-213x320.png, https:\/\/maloglaus.com\/wp-content\/uploads\/2025\/07\/Sans-titre-21-avril-2025-10.54.45-32-760500-426x640.png 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(max-width: 767px)\" \/>\n\n<source data-depicter-srcset=\"https:\/\/maloglaus.com\/wp-content\/uploads\/2025\/07\/Sans-titre-21-avril-2025-10.54.45-32-395x276.png, https:\/\/maloglaus.com\/wp-content\/uploads\/2025\/07\/Sans-titre-21-avril-2025-10.54.45-32-790x552.png 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(min-width: 768px)\" \/>\n<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-depicter-src=\"https:\/\/maloglaus.com\/wp-content\/uploads\/2025\/07\/Sans-titre-21-avril-2025-10.54.45-32-760500-395x276.png\" alt=\"\" \/>\n<\/picture>\n<a href=\"https:\/\/maloglaus.com\/en\/panier\/\"><p id=\"depicter-149-element-35\" class=\"depicter-element depicter-layer depicter-149-element-35\" data-type=\"text\" data-wrap=\"true\" data-name=\"Text 14\" data-local-id=\"element-35\" data-offset=\"x:60px;y:60px;origin:tl\" data-mobile-offset=\"x:-17px;y:148px;origin:mc\" data-width=\"auto,,269px\" data-height=\"auto,,auto\" data-responsive-scale=\"true,,\" data-frame-class=\"depicter-149-element-35-frame\">Mise en page de livres &amp; magazines<\/p><\/a>\n<\/div>\n<\/div>\n<script>\n(window.depicterSetups = window.depicterSetups || []).push(function(){\n\tDepicter.basePath = 'https:\/\/maloglaus.com\/wp-content\/plugins\/depicter\/resources\/scripts\/player\/';\n\tconst dpPlayer = Depicter.setup('.depicter-149',\n\t\t{\"width\":[\"1200\",\"1024\",\"360\"],\"height\":[\"700\",\"700\",\"740\"],\"view\":\"fade\",\"keepAspectRatio\":true,\"preload\":0,\"layout\":\"fullwidth\",\"rtl\":false,\"initAfterAppear\":false,\"ajaxApiUrl\":\"https:\\\/\\\/maloglaus.com\\\/wp-admin\\\/admin-ajax.php\",\"viewOptions\":{\"loop\":true},\"slideshow\":{\"duration\":3,\"pauseOnHover\":false,\"autostart\":true},\"mouseSwipe\":false,\"touchSwipe\":false,\"useWatermark\":false}\n\t);\n});\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e2bfd5d elementor-hidden-desktop elementor-hidden-tablet e-flex e-con-boxed e-con e-parent\" data-id=\"e2bfd5d\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b6af5cc elementor-widget elementor-widget-depicter_slider\" data-id=\"b6af5cc\" data-element_type=\"widget\" data-widget_type=\"depicter_slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<style id=\"depicter-109-inline-pre-css\">\n\n.depicter-109:not(.depicter-ready){\n\theight:700px;\n}\n\n\/***** Tablet *****\/\n@media screen and (max-width: 1024px){\n\n.depicter-109:not(.depicter-ready){\n\theight:700px;\n}\n\n}\n\/***** Mobile *****\/\n@media screen and (max-width: 767px){\n\n.depicter-109:not(.depicter-ready){\n\theight:740px;\n}\n\n}\n<\/style>\n<div id=\"depicter-109\" class=\"depicter depicter-document depicter-revert depicter-109 depicter-layout-fullwidth\">\n\n<div class=\"depicter-loading-container depicter-loading dotFlashing-dark\"><div class=\"depicter-loading-dark depicter-dot-flashing\">\n   <span><\/span>\n   <span><\/span>\n   <span><\/span>\n<\/div>\n<\/div>\n\n<div class=\"depicter-overlay-layers\">\n<a href=\"https:\/\/maloglaus.com\/en\/prestations-devis-site-web\/\"><h3 data-between-in-out=\"false\" data-mobile-animation-out=\"{'direction':'left','easing':'easeInOutCubic','duration':800,'movement':0,'type':'move'}\" id=\"depicter-109-element-3\" class=\"depicter-element depicter-layer depicter-109-element-3\" data-type=\"text\" data-wrap=\"true\" data-name=\"Text 1\" data-local-id=\"element-3\" data-offset=\"x:0px;y:0px;origin:tl\" data-mobile-offset=\"x:30px;y:441px;origin:tl\" data-position-type=\"absolute\" data-mobile-position-type=\"absolute\" data-hide-on-sections=\"depicter-109-section-1\" data-width=\"auto,,200px\" data-height=\"auto,,auto\" data-responsive-scale=\"true,,\">Prestation photo &amp; vid\u00e9o<\/h3><\/a>\n\n<a href=\"https:\/\/maloglaus.com\/en\/prestations-devis-site-web\/\"><h3 data-between-in-out=\"false\" data-mobile-animation-out=\"{'direction':'left','easing':'easeInOutCubic','duration':800,'movement':0,'type':'move'}\" id=\"depicter-109-element-4\" class=\"depicter-element depicter-layer depicter-109-element-4\" data-type=\"text\" data-wrap=\"true\" data-name=\"Text 2\" data-local-id=\"element-4\" data-offset=\"x:30px;y:30px;origin:tl\" data-mobile-offset=\"x:30px;y:470px;origin:tl\" data-position-type=\"absolute\" data-mobile-position-type=\"absolute\" data-hide-on-sections=\"depicter-109-section-5\" data-width=\"auto,,auto\" data-height=\"auto,,auto\" data-responsive-scale=\"true,,\">Website design<\/h3><\/a>\n\n<a href=\"https:\/\/maloglaus.com\/en\/prestations-devis-design-graphique\/\"><h3 data-between-in-out=\"false\" data-mobile-animation-out=\"{'direction':'left','easing':'easeInOutCubic','duration':800,'movement':0,'type':'move'}\" id=\"depicter-109-element-7\" class=\"depicter-element depicter-layer depicter-109-element-7\" data-type=\"text\" data-wrap=\"true\" data-name=\"Text 4\" data-local-id=\"element-7\" data-offset=\"x:60px;y:60px;origin:tl\" data-mobile-offset=\"x:30px;y:498px;origin:tl\" data-position-type=\"absolute\" data-mobile-position-type=\"absolute\" data-hide-on-sections=\"depicter-109-section-9\" data-width=\"auto,,auto\" data-height=\"auto,,auto\" data-responsive-scale=\"true,,\">Communication visuelle &amp; design graphique<\/h3><\/a>\n\n<h2 data-between-in-out=\"false\" id=\"depicter-109-element-29\" class=\"depicter-element depicter-layer depicter-109-element-29\" data-type=\"text\" data-wrap=\"true\" data-name=\"Text 14\" data-local-id=\"element-29\" data-offset=\"x:0px;y:0px;origin:tl\" data-mobile-offset=\"x:1px;y:11px;origin:tl\" data-position-type=\"absolute\" data-mobile-position-type=\"absolute\" data-width=\"auto,,329px\" data-height=\"auto,,auto\" data-responsive-scale=\"true,,\">PRESTATIONS &amp;<br>DEVIS<br><\/h2>\n\n<\/div>\n\n<div id=\"depicter-109-section-1\" class=\"depicter-section depicter-109-section-1\" data-name=\"Section 1\" data-type=\"section\" data-local-id=\"section-1\">\n<picture data-between-in-out=\"false\" data-mobile-animation-in=\"{'direction':'left','easing':'easeInOutExpo','duration':800,'movement':0,'type':'move'}\" id=\"depicter-109-element-2\" class=\"depicter-element depicter-layer depicter-109-element-2\" data-type=\"image\" data-wrap=\"true\" data-name=\"Image 1\" data-local-id=\"element-2\" data-offset=\"x:57px;y:3px;origin:tl\" data-mobile-offset=\"x:115px;y:84px;origin:tl\" data-width=\"395px,,215px\" data-height=\"592px,,321px\" data-responsive-scale=\"true,,\" data-crop=\"false\">\n<source data-depicter-srcset=\"https:\/\/maloglaus.com\/wp-content\/uploads\/2025\/05\/AFFICHE-scaled-e1748360591883-215x321.jpg, https:\/\/maloglaus.com\/wp-content\/uploads\/2025\/05\/AFFICHE-scaled-e1748360591883-430x642.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(max-width: 767px)\" \/>\n\n<source data-depicter-srcset=\"https:\/\/maloglaus.com\/wp-content\/uploads\/2025\/05\/AFFICHE-scaled-e1748360591883-395x592.jpg, https:\/\/maloglaus.com\/wp-content\/uploads\/2025\/05\/AFFICHE-scaled-e1748360591883-790x1184.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(min-width: 768px)\" \/>\n<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-depicter-src=\"https:\/\/maloglaus.com\/wp-content\/uploads\/2025\/05\/AFFICHE-scaled-e1748360591883-395x592.jpg\" alt=\"Affiche\" \/>\n<\/picture>\n<a href=\"https:\/\/maloglaus.com\/en\/prestations-devis-photo\/\"><p id=\"depicter-109-element-31\" class=\"depicter-element depicter-layer depicter-109-element-31\" data-type=\"text\" data-wrap=\"true\" data-name=\"Text 10\" data-local-id=\"element-31\" data-offset=\"x:0px;y:0px;origin:tl\" data-mobile-offset=\"x:-54px;y:81px;origin:mc\" data-width=\"auto,,auto\" data-height=\"auto,,auto\" data-responsive-scale=\"true,,\" data-frame-class=\"depicter-109-element-31-frame\">Prestation photo &amp; vid\u00e9o<\/p><\/a>\n<\/div>\n\n<div id=\"depicter-109-section-5\" class=\"depicter-section depicter-109-section-5\" data-name=\"Slide 1\" data-type=\"section\" data-local-id=\"section-5\">\n<picture data-between-in-out=\"false\" data-mobile-animation-in=\"{'direction':'left','easing':'easeInOutExpo','duration':800,'movement':0,'type':'move'}\" id=\"depicter-109-element-16\" class=\"depicter-element depicter-layer depicter-109-element-16\" data-type=\"image\" data-wrap=\"true\" data-name=\"Image 4\" data-local-id=\"element-16\" data-offset=\"x:57px;y:3px;origin:tl\" data-mobile-offset=\"x:115px;y:84px;origin:tl\" data-width=\"395px,,213px\" data-height=\"592px,,320px\" data-responsive-scale=\"true,,\" data-crop=\"false\">\n<source data-depicter-srcset=\"https:\/\/maloglaus.com\/wp-content\/uploads\/2025\/05\/AFFICHE-SRC-scaled-e1748201216607-213x320.jpg, https:\/\/maloglaus.com\/wp-content\/uploads\/2025\/05\/AFFICHE-SRC-scaled-e1748201216607-426x640.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(max-width: 767px)\" \/>\n\n<source data-depicter-srcset=\"https:\/\/maloglaus.com\/wp-content\/uploads\/2025\/05\/AFFICHE-SRC-scaled-e1748201216607-395x493.jpg, https:\/\/maloglaus.com\/wp-content\/uploads\/2025\/05\/AFFICHE-SRC-scaled-e1748201216607-790x986.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(min-width: 768px)\" \/>\n<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-depicter-src=\"https:\/\/maloglaus.com\/wp-content\/uploads\/2025\/05\/AFFICHE-SRC-scaled-e1748201216607-395x493.jpg\" alt=\"Affiche src\" \/>\n<\/picture>\n<a href=\"https:\/\/maloglaus.com\/en\/prestations-devis-site-web\/\"><p id=\"depicter-109-element-33\" class=\"depicter-element depicter-layer depicter-109-element-33\" data-type=\"text\" data-wrap=\"true\" data-name=\"Text 12\" data-local-id=\"element-33\" data-offset=\"x:30px;y:30px;origin:tl\" data-mobile-offset=\"x:-16px;y:110px;origin:mc\" data-width=\"auto,,269px\" data-height=\"auto,,auto\" data-responsive-scale=\"true,,\" data-frame-class=\"depicter-109-element-33-frame\">Website design<\/p><\/a>\n<\/div>\n\n<div id=\"depicter-109-section-9\" class=\"depicter-section depicter-109-section-9\" data-name=\"Slide 2\" data-type=\"section\" data-local-id=\"section-9\">\n<picture data-between-in-out=\"false\" data-mobile-animation-in=\"{'direction':'left','easing':'easeInOutExpo','duration':800,'movement':0,'type':'move'}\" id=\"depicter-109-element-18\" class=\"depicter-element depicter-layer depicter-109-element-18\" data-type=\"image\" data-wrap=\"true\" data-name=\"Image 6\" data-local-id=\"element-18\" data-offset=\"x:57px;y:3px;origin:tl\" data-mobile-offset=\"x:115px;y:84px;origin:tl\" data-width=\"395px,,213px\" data-height=\"592px,,320px\" data-responsive-scale=\"true,,\" data-crop=\"false\">\n<source data-depicter-srcset=\"https:\/\/maloglaus.com\/wp-content\/uploads\/2025\/11\/livre-3-scaled-e1762804696607-213x320.jpg, https:\/\/maloglaus.com\/wp-content\/uploads\/2025\/11\/livre-3-scaled-e1762804696607-426x640.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(max-width: 767px)\" \/>\n\n<source data-depicter-srcset=\"https:\/\/maloglaus.com\/wp-content\/uploads\/2025\/11\/livre-3-scaled-e1762804696607-395x263.jpg, https:\/\/maloglaus.com\/wp-content\/uploads\/2025\/11\/livre-3-scaled-e1762804696607-790x526.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(min-width: 768px)\" \/>\n<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-depicter-src=\"https:\/\/maloglaus.com\/wp-content\/uploads\/2025\/11\/livre-3-scaled-e1762804696607-395x263.jpg\" alt=\"Livre\" \/>\n<\/picture>\n<a href=\"https:\/\/maloglaus.com\/en\/prestations-devis-design-graphique\/\"><p id=\"depicter-109-element-35\" class=\"depicter-element depicter-layer depicter-109-element-35\" data-type=\"text\" data-wrap=\"true\" data-name=\"Text 14\" data-local-id=\"element-35\" data-offset=\"x:60px;y:60px;origin:tl\" data-mobile-offset=\"x:4px;y:148px;origin:mc\" data-width=\"auto,,311px\" data-height=\"auto,,auto\" data-responsive-scale=\"true,,\" data-frame-class=\"depicter-109-element-35-frame\">Communication visuelle &amp; design graphique<\/p><\/a>\n<\/div>\n<\/div>\n<script>\n(window.depicterSetups = window.depicterSetups || []).push(function(){\n\tDepicter.basePath = 'https:\/\/maloglaus.com\/wp-content\/plugins\/depicter\/resources\/scripts\/player\/';\n\tconst dpPlayer = Depicter.setup('.depicter-109',\n\t\t{\"width\":[\"1200\",\"1024\",\"360\"],\"height\":[\"700\",\"700\",\"740\"],\"view\":\"fade\",\"keepAspectRatio\":true,\"preload\":0,\"layout\":\"fullwidth\",\"rtl\":false,\"initAfterAppear\":false,\"ajaxApiUrl\":\"https:\\\/\\\/maloglaus.com\\\/wp-admin\\\/admin-ajax.php\",\"viewOptions\":{\"loop\":true},\"slideshow\":{\"duration\":3,\"pauseOnHover\":false,\"autostart\":true},\"mouseSwipe\":false,\"touchSwipe\":false,\"useWatermark\":false}\n\t);\n});\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2585d14 elementor-hidden-desktop elementor-hidden-tablet e-flex e-con-boxed e-con e-parent\" data-id=\"2585d14\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ca07315 elementor-widget elementor-widget-depicter_slider\" data-id=\"ca07315\" data-element_type=\"widget\" data-widget_type=\"depicter_slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<style id=\"depicter-114-inline-pre-css\">\n\n.depicter-114:not(.depicter-ready){\n\theight:700px;\n}\n\n\/***** Tablet *****\/\n@media screen and (max-width: 1024px){\n\n.depicter-114:not(.depicter-ready){\n\theight:700px;\n}\n\n}\n\/***** Mobile *****\/\n@media screen and (max-width: 767px){\n\n.depicter-114:not(.depicter-ready){\n\theight:740px;\n}\n\n}\n<\/style>\n<div id=\"depicter-114\" class=\"depicter depicter-document depicter-revert depicter-114 depicter-layout-fullwidth\">\n\n<div class=\"depicter-loading-container depicter-loading dotFlashing-dark\"><div class=\"depicter-loading-dark depicter-dot-flashing\">\n   <span><\/span>\n   <span><\/span>\n   <span><\/span>\n<\/div>\n<\/div>\n\n<div class=\"depicter-overlay-layers\">\n<a href=\"https:\/\/maloglaus.com\/en\/biographie\/\"><h3 data-between-in-out=\"false\" data-mobile-animation-out=\"{'direction':'left','easing':'easeInOutCubic','duration':800,'movement':0,'type':'move'}\" id=\"depicter-114-element-3\" class=\"depicter-element depicter-layer depicter-114-element-3\" data-type=\"text\" data-wrap=\"true\" data-name=\"Text 1\" data-local-id=\"element-3\" data-offset=\"x:0px;y:0px;origin:tl\" data-mobile-offset=\"x:30px;y:441px;origin:tl\" data-position-type=\"absolute\" data-mobile-position-type=\"absolute\" data-hide-on-sections=\"depicter-114-section-1\" data-width=\"auto,,149px\" data-height=\"auto,,auto\" data-responsive-scale=\"true,,\">Biography<\/h3><\/a>\n\n<a href=\"https:\/\/maloglaus.com\/en\/contact\/\"><h3 data-between-in-out=\"false\" data-mobile-animation-out=\"{'direction':'left','easing':'easeInOutCubic','duration':800,'movement':0,'type':'move'}\" id=\"depicter-114-element-4\" class=\"depicter-element depicter-layer depicter-114-element-4\" data-type=\"text\" data-wrap=\"true\" data-name=\"Text 2\" data-local-id=\"element-4\" data-offset=\"x:30px;y:30px;origin:tl\" data-mobile-offset=\"x:30px;y:470px;origin:tl\" data-position-type=\"absolute\" data-mobile-position-type=\"absolute\" data-hide-on-sections=\"depicter-114-section-5\" data-width=\"auto,,auto\" data-height=\"auto,,auto\" data-responsive-scale=\"true,,\">Contact<\/h3><\/a>\n\n<h2 data-between-in-out=\"false\" id=\"depicter-114-element-29\" class=\"depicter-element depicter-layer depicter-114-element-29\" data-type=\"text\" data-wrap=\"true\" data-name=\"Text 14\" data-local-id=\"element-29\" data-offset=\"x:0px;y:0px;origin:tl\" data-mobile-offset=\"x:1px;y:15px;origin:tl\" data-position-type=\"absolute\" data-mobile-position-type=\"absolute\" data-width=\"auto,,329px\" data-height=\"auto,,auto\" data-responsive-scale=\"true,,\">ABOUT<\/h2>\n\n<\/div>\n\n<div id=\"depicter-114-section-1\" class=\"depicter-section depicter-114-section-1\" data-name=\"Section 1\" data-type=\"section\" data-local-id=\"section-1\">\n<picture data-between-in-out=\"false\" data-mobile-animation-in=\"{'direction':'left','easing':'easeInOutExpo','duration':800,'movement':0,'type':'move'}\" id=\"depicter-114-element-2\" class=\"depicter-element depicter-layer depicter-114-element-2\" data-type=\"image\" data-wrap=\"true\" data-name=\"Image 1\" data-local-id=\"element-2\" data-offset=\"x:57px;y:3px;origin:tl\" data-mobile-offset=\"x:115px;y:84px;origin:tl\" data-width=\"395px,,215px\" data-height=\"592px,,321px\" data-responsive-scale=\"true,,\" data-crop=\"false\">\n<source data-depicter-srcset=\"https:\/\/maloglaus.com\/wp-content\/uploads\/2025\/08\/DSC06943-scaled-215x321.jpg, https:\/\/maloglaus.com\/wp-content\/uploads\/2025\/08\/DSC06943-scaled-430x642.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(max-width: 767px)\" \/>\n\n<source data-depicter-srcset=\"https:\/\/maloglaus.com\/wp-content\/uploads\/2025\/08\/DSC06943-scaled-395x592.jpg, https:\/\/maloglaus.com\/wp-content\/uploads\/2025\/08\/DSC06943-scaled-790x1184.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(min-width: 768px)\" \/>\n<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-depicter-src=\"https:\/\/maloglaus.com\/wp-content\/uploads\/2025\/08\/DSC06943-scaled-395x592.jpg\" alt=\"Malo Glaus Autoportrait\" \/>\n<\/picture>\n<a href=\"https:\/\/maloglaus.com\/en\/biographie\/\"><h3 id=\"depicter-114-element-31\" class=\"depicter-element depicter-layer depicter-114-element-31\" data-type=\"text\" data-wrap=\"true\" data-name=\"Text 10\" data-local-id=\"element-31\" data-offset=\"x:0px;y:0px;origin:tl\" data-mobile-offset=\"x:-106px;y:81px;origin:mc\" data-width=\"auto,,auto\" data-height=\"auto,,auto\" data-responsive-scale=\"true,,\" data-frame-class=\"depicter-114-element-31-frame\">Biography<\/h3><\/a>\n<\/div>\n\n<div id=\"depicter-114-section-5\" class=\"depicter-section depicter-114-section-5\" data-name=\"Slide 1\" data-type=\"section\" data-local-id=\"section-5\">\n<picture data-between-in-out=\"false\" data-mobile-animation-in=\"{'direction':'left','easing':'easeInOutExpo','duration':800,'movement':0,'type':'move'}\" id=\"depicter-114-element-16\" class=\"depicter-element depicter-layer depicter-114-element-16\" data-type=\"image\" data-wrap=\"true\" data-name=\"Image 4\" data-local-id=\"element-16\" data-offset=\"x:57px;y:3px;origin:tl\" data-mobile-offset=\"x:115px;y:84px;origin:tl\" data-width=\"395px,,213px\" data-height=\"592px,,320px\" data-responsive-scale=\"true,,\" data-crop=\"false\">\n<source data-depicter-srcset=\"https:\/\/maloglaus.com\/wp-content\/uploads\/2024\/03\/surf-boy-2-213x320.jpg, https:\/\/maloglaus.com\/wp-content\/uploads\/2024\/03\/surf-boy-2-426x640.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(max-width: 767px)\" \/>\n\n<source data-depicter-srcset=\"https:\/\/maloglaus.com\/wp-content\/uploads\/2024\/03\/surf-boy-2-329x493.jpg, https:\/\/maloglaus.com\/wp-content\/uploads\/2024\/03\/surf-boy-2-658x986.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(min-width: 768px)\" \/>\n<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-depicter-src=\"https:\/\/maloglaus.com\/wp-content\/uploads\/2024\/03\/surf-boy-2-329x493.jpg\" alt=\"Photographie de surfeur \u00e0 Biarritz\" \/>\n<\/picture>\n<a href=\"https:\/\/maloglaus.com\/en\/contact\/\"><h3 id=\"depicter-114-element-33\" class=\"depicter-element depicter-layer depicter-114-element-33\" data-type=\"text\" data-wrap=\"true\" data-name=\"Text 12\" data-local-id=\"element-33\" data-offset=\"x:30px;y:30px;origin:tl\" data-mobile-offset=\"x:-16px;y:110px;origin:mc\" data-width=\"auto,,269px\" data-height=\"auto,,auto\" data-responsive-scale=\"true,,\" data-frame-class=\"depicter-114-element-33-frame\">Contact<\/h3><\/a>\n<\/div>\n<\/div>\n<script>\n(window.depicterSetups = window.depicterSetups || []).push(function(){\n\tDepicter.basePath = 'https:\/\/maloglaus.com\/wp-content\/plugins\/depicter\/resources\/scripts\/player\/';\n\tconst dpPlayer = Depicter.setup('.depicter-114',\n\t\t{\"width\":[\"1200\",\"1024\",\"360\"],\"height\":[\"700\",\"700\",\"740\"],\"view\":\"fade\",\"keepAspectRatio\":true,\"preload\":0,\"layout\":\"fullwidth\",\"rtl\":false,\"initAfterAppear\":false,\"ajaxApiUrl\":\"https:\\\/\\\/maloglaus.com\\\/wp-admin\\\/admin-ajax.php\",\"viewOptions\":{\"loop\":true},\"slideshow\":{\"duration\":3,\"pauseOnHover\":false,\"autostart\":true},\"mouseSwipe\":false,\"touchSwipe\":false,\"useWatermark\":false}\n\t);\n});\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b5c96ff e-flex e-con-boxed e-con e-parent\" data-id=\"b5c96ff\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4125762 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"4125762\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<a class=\"elementor-element elementor-element-4e1d75f e-con-full elementor-hidden-mobile e-flex e-con e-child\" data-id=\"4e1d75f\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" href=\"https:\/\/maloglaus.com\/en\/\">\n\t\t\t\t<\/a>\n\t\t<div class=\"elementor-element elementor-element-4698fe5 e-flex e-con-boxed e-con e-parent\" data-id=\"4698fe5\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-604ba4d elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"604ba4d\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-29721c0 elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"29721c0\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c2baa01 elementor-widget elementor-widget-n-accordion\" data-id=\"c2baa01\" data-element_type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;all_collapsed&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2040\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2040\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><h3 class=\"e-n-accordion-item-title-text\"> FAQ <\/h3><\/span>\n\t\t\t\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2040\" class=\"elementor-element elementor-element-78b1174 e-flex e-con-boxed e-con e-child\" data-id=\"78b1174\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2040\" class=\"elementor-element elementor-element-632a32a e-con-full e-flex e-con e-child\" data-id=\"632a32a\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3a5f2ca elementor-widget elementor-widget-heading\" data-id=\"3a5f2ca\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Quels services proposez-vous en tant que designer graphique ?\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9fecc77 elementor-widget elementor-widget-text-editor\" data-id=\"9fecc77\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4>Je propose des services de communication visuelle et de design graphique, incluant la cr\u00e9ation d&rsquo;identit\u00e9 graphique, le design pour supports imprim\u00e9s et textiles, et la conception de supports digitaux.<\/h4>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2040\" class=\"elementor-element elementor-element-b2f9786 e-con-full e-flex e-con e-child\" data-id=\"b2f9786\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-590da46 elementor-widget elementor-widget-heading\" data-id=\"590da46\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Quels services proposez-vous en tant que cr\u00e9ateur de sites web ?\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-62d09d6 elementor-widget elementor-widget-text-editor\" data-id=\"62d09d6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4>Je propose des services de cr\u00e9ation de sites web, incluant la conception de sites vitrine, de sites e-commerce, et de sites personnalis\u00e9s. Je m&rsquo;occupe de tout, de la conception \u00e0 la mise en ligne, en passant par le r\u00e9f\u00e9rencement et l&rsquo;h\u00e9bergement.<\/h4><h4>Je r\u00e9alise \u00e9galement de la conception de site web<\/h4>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2040\" class=\"elementor-element elementor-element-7edf279 e-con-full e-flex e-con e-child\" data-id=\"7edf279\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e70747f elementor-widget elementor-widget-heading\" data-id=\"e70747f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Quels types de projets r\u00e9alisez-vous ?\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a200746 elementor-widget elementor-widget-text-editor\" data-id=\"a200746\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4>Je r\u00e9alise des projets vari\u00e9s, allant de la cr\u00e9ation de logos et de chartes graphiques \u00e0 la conception de supports imprim\u00e9s (affiches, cartes de visite, flyers) et de supports digitaux (banni\u00e8res web, visuels pour r\u00e9seaux sociaux).<\/h4><h4>\u00a0<\/h4><h4>Je r\u00e9alise des sites vitrine, des sites e-commerce, des blogs, et des sites personnalis\u00e9s pour r\u00e9pondre \u00e0 vos besoins sp\u00e9cifiques. Chaque site est con\u00e7u pour \u00eatre responsive, s\u00e9curis\u00e9 et optimis\u00e9 pour les moteurs de recherche.<\/h4>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2040\" class=\"elementor-element elementor-element-7a1e5e9 e-con-full e-flex e-con e-child\" data-id=\"7a1e5e9\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-279b5dd elementor-widget elementor-widget-heading\" data-id=\"279b5dd\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Comment se d\u00e9roule un projet de communication visuelle ?\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-69740f6 elementor-widget elementor-widget-text-editor\" data-id=\"69740f6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4>Chaque projet commence par une discussion pour comprendre vos besoins et vos attentes. Ensuite, je d\u00e9veloppe des concepts et des maquettes que je vous pr\u00e9sente pour feedback. Une fois que vous \u00eates satisfait, je finalise les designs et je vous les livre dans le format souhait\u00e9.<\/h4>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2040\" class=\"elementor-element elementor-element-006418e e-con-full e-flex e-con e-child\" data-id=\"006418e\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0c27278 elementor-widget elementor-widget-heading\" data-id=\"0c27278\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Offrez-vous des services de maintenance et de mise \u00e0 jour ?\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-100e840 elementor-widget elementor-widget-text-editor\" data-id=\"100e840\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4>Oui, je propose des services de maintenance et de mise \u00e0 jour pour garantir que votre site reste \u00e0 jour, s\u00e9curis\u00e9 et performant.<\/h4>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2040\" class=\"elementor-element elementor-element-84e9d7b e-con-full e-flex e-con e-child\" data-id=\"84e9d7b\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2645c33 elementor-widget elementor-widget-heading\" data-id=\"2645c33\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Quels sont vos tarifs ?\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-50f0a11 elementor-widget elementor-widget-text-editor\" data-id=\"50f0a11\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4>Mes tarifs varient en fonction de la complexit\u00e9 et de l&rsquo;ampleur du projet. Je vous invite \u00e0 me contacter pour <a href=\"https:\/\/maloglaus.com\/en\/prestations-devis-site-web\/\"><span style=\"text-decoration: underline;\">obtenir un devis personnalis\u00e9<\/span><\/a>.<\/h4>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2040\" class=\"elementor-element elementor-element-67049e7 e-con-full e-flex e-con e-child\" data-id=\"67049e7\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8abb7ef elementor-widget elementor-widget-heading\" data-id=\"8abb7ef\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Comment puis-je vous contacter pour discuter d'un projet ?\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aa16fd0 elementor-widget elementor-widget-text-editor\" data-id=\"aa16fd0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4>Vous pouvez me contacter par <span style=\"text-decoration: underline;\"><a href=\"https:\/\/maloglaus.com\/en\/contact\/\">email ou t\u00e9l\u00e9phone<\/a><\/span>. Je suis toujours disponible pour discuter de vos besoins et de vos id\u00e9es.<\/h4>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2040\" class=\"elementor-element elementor-element-6afbec6 e-con-full e-flex e-con e-child\" data-id=\"6afbec6\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a94843c elementor-widget elementor-widget-heading\" data-id=\"a94843c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Quels sont les droits d'utilisation des cr\u00e9ations graphiques ?\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0ac1eb8 elementor-widget elementor-widget-text-editor\" data-id=\"0ac1eb8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4>Les contenus remis restent ma propri\u00e9t\u00e9 exclusive conform\u00e9ment aux articles L.111-1 et suivants du Code de la propri\u00e9t\u00e9 intellectuelle. Toute utilisation commerciale, reproduction ou diffusion est conditionn\u00e9e \u00e0 une cession de droits d&rsquo;auteur \u00e9crite.<\/h4>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2040\" class=\"elementor-element elementor-element-0e10b49 e-con-full e-flex e-con e-child\" data-id=\"0e10b49\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d611aa1 elementor-widget elementor-widget-heading\" data-id=\"d611aa1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Travaillez-vous avec des marques ou des particuliers ?\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e14415e elementor-widget elementor-widget-text-editor\" data-id=\"e14415e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4>Je travaille principalement avec des marques, des entreprises, des \u00e9v\u00e9nements, et plus occasionnellement des particuliers. Que vous soyez un professionnel ou un passionn\u00e9, je suis l\u00e0 pour capturer vos moments et vos projets.<\/h4>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2040\" class=\"elementor-element elementor-element-64720cd e-con-full e-flex e-con e-child\" data-id=\"64720cd\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1f7e8c5 elementor-widget elementor-widget-heading\" data-id=\"1f7e8c5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Pouvez-vous voyager pour des projets ?\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-76007b3 elementor-widget elementor-widget-text-editor\" data-id=\"76007b3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4>Oui, je suis disponible pour voyager dans le monde entier pour des projets.<\/h4>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2040\" class=\"elementor-element elementor-element-a35acd0 e-con-full e-flex e-con e-child\" data-id=\"a35acd0\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8780e8f elementor-widget elementor-widget-heading\" data-id=\"8780e8f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Comment puis-je voir vos travaux pr\u00e9c\u00e9dents ?\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b33580d elementor-widget elementor-widget-text-editor\" data-id=\"b33580d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4>Vous pouvez consulter mon portfolio sur ce site pour voir des exemples de mes travaux pr\u00e9c\u00e9dents. Cela vous donnera une id\u00e9e de mon style et de mes comp\u00e9tences.<\/h4>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2040\" class=\"elementor-element elementor-element-afc05d0 e-con-full e-flex e-con e-child\" data-id=\"afc05d0\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-db0bc7b elementor-widget elementor-widget-heading\" data-id=\"db0bc7b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Quels sont vos horaires de travail ?\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e173557 elementor-widget elementor-widget-text-editor\" data-id=\"e173557\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4>Photographe est un m\u00e9tier n\u00e9cessitant d&rsquo;avoir des horaires flexibles. je m&rsquo;adapte donc \u00e0 vos besoins, \u00e0 tout heure, tous les jours de la semaine.<\/h4>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>MALO GLAUS | Communication visuelle COMMUNICATION VISUELLE Unstpbl Trace Lab Fire Sens PRESTATIONS &amp; DEVIS Prestations photo &amp; vid\u00e9o Conception de site web Communication visuelle et design graphique \u00c0 PROPOS Biographie Contact \u00a0 ! This slider has unpublished changes. Publish the changes to see the final result.Open the editor and publish now. This notice is&#8230;<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":"","_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"enable","_kad_post_title":"hide","_kad_post_layout":"fullwidth","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","slim_seo":{"title":"Malo Glaus | Communication visuelle","description":"MALO GLAUS COMMUNICATION VISUELLE Conception de site web Graphisme Conception de livres &amp; magazines Retouche photo PRESTATIONS &a"},"footnotes":""},"class_list":["post-7709","page","type-page","status-publish","hentry"],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"trp-custom-language-flag":false,"depicter-thumbnail":false,"woocommerce_thumbnail":false,"woocommerce_single":false,"woocommerce_gallery_thumbnail":false},"uagb_author_info":{"display_name":"Malo GLAUS","author_link":"https:\/\/maloglaus.com\/en\/author\/maloglaus\/"},"uagb_comment_info":0,"uagb_excerpt":"MALO GLAUS | Communication visuelle COMMUNICATION VISUELLE Unstpbl Trace Lab Fire Sens PRESTATIONS &amp; DEVIS Prestations photo &amp; vid\u00e9o Conception de site web Communication visuelle et design graphique \u00c0 PROPOS Biographie Contact \u00a0 ! This slider has unpublished changes. Publish the changes to see the final result.Open the editor and publish now. This notice is...","_links":{"self":[{"href":"https:\/\/maloglaus.com\/en\/wp-json\/wp\/v2\/pages\/7709","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maloglaus.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/maloglaus.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/maloglaus.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maloglaus.com\/en\/wp-json\/wp\/v2\/comments?post=7709"}],"version-history":[{"count":145,"href":"https:\/\/maloglaus.com\/en\/wp-json\/wp\/v2\/pages\/7709\/revisions"}],"predecessor-version":[{"id":8789,"href":"https:\/\/maloglaus.com\/en\/wp-json\/wp\/v2\/pages\/7709\/revisions\/8789"}],"wp:attachment":[{"href":"https:\/\/maloglaus.com\/en\/wp-json\/wp\/v2\/media?parent=7709"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}